{"text_format":"1","workbook":"xlsx","n_sheets":5,"sheets":["Overview","NPV tool","LTSR","Sold","Data"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":0,"defined_names":0,"comments":1,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Overview","index":0,"n_rows":15,"n_cols":2,"rows_kept":15,"cut":false,"hidden":false,"merged":[[1,1,2,1],[11,1,12,1]]}
[]
[null,"NPV Tool - User Guidance"]
[]
[null,"Certain user inputs  are required in the white cells in the 'NPV tool' tab, for the tool to function correctly: 1) the Entry Point, 2) Project Cost, 3) first capacity quarter and 4) capacity profile. User inputs are required on the 'NPV tool' tab only."]
[null,"NPV tool Tab - Used to calculate the value of the market signal.\nIf this is greater than or equal to 50% of the project cost then the Net Present Value (NPV) test shall be passed. If the value is lower than 50% then a premium will be the lowest price (to 4 decimal places) that can be added to the Reserve Price to allow the NPV test to be passed."]
[null,"LTSR Tab - Long Term Summary Report which contains the Allocation of Obligated Entry Capacity and Release Obligation Summary"]
[null,"Sold Tab - Quantity of capacity sold at a specific point in time"]
[null,"Data Tab - Contains the latest published prices for each of the different Entry points"]
[null,"If you have any queries about this tool then please contact ntsinvestment@nationalgrid.com"]
[]
[]
[null,"NPV Tool - Version History"]
[]
[1,"Initial version of this tool published alongside v5.0 of the Entry Capacity Release methdology statement."]
[1.1000000000000001,"22/10/19 - ''LTSR' & 'Sold' tabs updated with latest available data."]

{"sheet":"NPV tool","index":1,"n_rows":41,"n_cols":62,"rows_kept":41,"cut":false,"hidden":false,"merged":[[10,3,10,8],[5,3,5,8],[6,3,6,8],[7,3,7,8],[8,3,8,8],[9,3,9,8]]}
[null,"(User Revenue) >= (f-factor)*(estimated increase in allowed revenue)"]
[]
[null,"Entry Point ","Avonmouth"]
[]
[null,"Input","Value","Description"]
[null,"Project Cost (£)",null,"National Grid to determine Project Cost in accordance with the Entry Capacity Release (ECR) methodology statement."]
[null,"Sharing Factor",0.5,"as defined in the ECR"]
[null,"User Commitment (£)",{"$f":"C6*C7","v":0},"calculation"]
[null,"Discount Rate - Annual",7.85E-2,"as defined in the ECR (5.05% + inflation)."]
[null,"Discount Rate - Quarterly",{"$f":"((1+C9)^(1/4)-1)","v":1.907239484965717E-2}]
[null,"User Revenue NPV (£)",{"$f":"C30","v":0},"calculation"]
[]
[null,"Capacity Profile & revenue",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25,26,27,28,29,30,31,32,33,34,35,36,37,38,39,40,41,42,43,44,45,46,47,48,49,50,51,52,53,54,55,56,57,58,59,60]
[null,"Quarter","Y1 Q1","Y1 Q2","Y1 Q3","Y1 Q4","Y2 Q1","Y2 Q2","Y2 Q3","Y2 Q4","Y3 Q1","Y3 Q2","Y3 Q3","Y3 Q4","Y4 Q1","Y4 Q2","Y4 Q3","Y4 Q4","Y5 Q1","Y5 Q2","Y5 Q3","Y5 Q4","Y6 Q1","Y6 Q2","Y6 Q3","Y6 Q4","Y7 Q1","Y7 Q2","Y7 Q3","Y7 Q4","Y8 Q1","Y8 Q2","Y8 Q3","Y8 Q4","Y9 Q1","Y9 Q2","Y9 Q3","Y9 Q4","Y10 Q1","Y10 Q2","Y10 Q3","Y10 Q4","Y11 Q1","Y11 Q2","Y11 Q3","Y11 Q4","Y12 Q1","Y12 Q2","Y12 Q3","Y12 Q4","Y13 Q1","Y13 Q2","Y13 Q3","Y13 Q4","Y14 Q1","Y14 Q2","Y14 Q3","Y14 Q4","Y15 Q1","Y15 Q2","Y15 Q3","Y15 Q4"]
[null,"Start of Quarter","2020-10-01",{"$f":"EDATE(C15,3)","v":"2021-01-01"},{"$f":"EDATE(D15,3)","v":"2021-04-01"},{"$f":"EDATE(E15,3)","v":"2021-07-01"},"2021-10-01","2022-01-01","2022-04-01","2022-07-01","2022-10-01","2023-01-01","2023-04-01","2023-07-01","2023-10-01","2024-01-01","2024-04-01","2024-07-01","2024-10-01","2025-01-01","2025-04-01","2025-07-01","2025-10-01","2026-01-01","2026-04-01","2026-07-01","2026-10-01","2027-01-01","2027-04-01","2027-07-01","2027-10-01","2028-01-01","2028-04-01","2028-07-01","2028-10-01","2029-01-01","2029-04-01","2029-07-01","2029-10-01","2030-01-01","2030-04-01","2030-07-01","2030-10-01","2031-01-01","2031-04-01","2031-07-01","2031-10-01","2032-01-01","2032-04-01","2032-07-01","2032-10-01","2033-01-01","2033-04-01","2033-07-01","2033-10-01","2034-01-01","2034-04-01","2034-07-01","2034-10-01","2035-01-01","2035-04-01","2035-07-01"]
[null,"End of Quarter",{"$f":"EDATE(C15,3)-1","v":"2020-12-31"},{"$f":"EDATE(D15,3)-1","v":"2021-03-31"},"2021-06-30","2021-09-30","2021-12-31","2022-03-31","2022-06-30","2022-09-30","2022-12-31","2023-03-31","2023-06-30","2023-09-30","2023-12-31","2024-03-31","2024-06-30","2024-09-30","2024-12-31","2025-03-31","2025-06-30","2025-09-30","2025-12-31","2026-03-31","2026-06-30","2026-09-30","2026-12-31","2027-03-31","2027-06-30","2027-09-30","2027-12-31","2028-03-31","2028-06-30","2028-09-30","2028-12-31","2029-03-31","2029-06-30","2029-09-30","2029-12-31","2030-03-31","2030-06-30","2030-09-30","2030-12-31","2031-03-31","2031-06-30","2031-09-30","2031-12-31","2032-03-31","2032-06-30","2032-09-30","2032-12-31","2033-03-31","2033-06-30","2033-09-30","2033-12-31","2034-03-31","2034-06-30","2034-09-30","2034-12-31","2035-03-31","2035-06-30","2035-09-30"]
[null,"Days in Quarter",{"$f":"C16-C15+1","v":92},{"$f":"D16-D15+1","v":90},{"$f":"E16-E15+1","v":91},92,92,90,91,92,92,90,91,92,92,91,91,92,92,90,91,92,92,90,91,92,92,90,91,92,92,91,91,92,92,90,91,92,92,90,91,92,92,90,91,92,92,91,91,92,92,90,91,92,92,90,91,92,92,90,91,92]
[null,"Capacity requested (kWh/d)"]
[null,"Non-Incremental (kWh/d)",{"$f":"IFERROR(VLOOKUP(C15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(D15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(E15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(F15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(G15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(H15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(I15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(J15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(K15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(L15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(M15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(N15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(O15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(P15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(Q15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(R15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(S15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(T15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(U15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(V15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(W15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(X15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(Y15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(Z15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AA15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AB15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AC15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AD15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AE15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AF15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AG15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AH15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AI15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AJ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AK15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AL15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AM15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AN15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AO15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AP15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AQ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AR15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AS15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AT15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AU15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AV15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AW15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AX15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AY15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(AZ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BA15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BB15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BC15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BD15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BE15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BF15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BG15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BH15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BI15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000},{"$f":"IFERROR(VLOOKUP(BJ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)-1,0),0)","v":179300000}]
[null,"Incremental (kWh/d)",{"$f":"IFERROR(VLOOKUP(C15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(D15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(E15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(F15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(G15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(H15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(I15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(J15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(K15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(L15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(M15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(N15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(O15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(P15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(Q15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(R15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(S15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(T15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(U15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(V15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(W15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(X15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(Y15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(Z15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AA15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AB15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AC15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AD15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AE15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AF15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AG15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AH15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AI15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AJ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AK15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AL15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AM15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AN15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AO15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AP15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AQ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AR15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AS15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AT15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AU15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AV15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AW15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AX15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AY15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AZ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BA15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BB15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BC15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BD15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BE15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BF15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BG15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BH15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BI15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BJ15,LTSR!$B:$CX,MATCH($C$3,LTSR!7:7,0)+1,0),0)","v":0}]
[null,"Sold Capacity (kWh/d)",{"$f":"IFERROR(VLOOKUP(C15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(D15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(E15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(F15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(G15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(H15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(I15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(J15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(K15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(L15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(M15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(N15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(O15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(P15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(Q15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(R15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(S15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(T15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(U15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(V15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(W15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(X15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(Y15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(Z15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AA15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AB15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AC15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AD15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AE15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AF15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AG15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AH15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AI15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AJ15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AK15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AL15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AM15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AN15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AO15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AP15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AQ15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AR15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AS15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AT15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AU15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AV15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AW15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AX15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AY15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(AZ15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BA15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BB15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BC15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BD15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BE15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BF15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BG15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BH15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BI15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0},{"$f":"IFERROR(VLOOKUP(BJ15,Sold!$B:$DW,MATCH($C$3,Sold!7:7,0),0),0)","v":0}]
[null,"Withheld (kWh/d)",{"$f":"(MIN(C19-C21,0.1*C19))","v":17930000},{"$f":"(MIN(D19-D21,0.1*D19))","v":17930000},17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,{"$f":"0.1*Y19","v":17930000},17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000,17930000]
[null,"Available Capacity (kWh/d)",{"$f":"C19+C20-C21-C22","v":161370000},{"$f":"D19+D20-D21-D22","v":161370000},161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000]
[null,"Existing Capacity Requested (kWh/d)",{"$f":"MIN(C18,MAX(C23,0))","v":161370000},{"$f":"MIN(D18,MAX(D23,0))","v":161370000},161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000,161370000]
[null,"New Incremental Requested (kWh/d)",{"$f":"MAX(0,C18-C24)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"MAX(0,AI18-AI24)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,"Capacity Requested (kWh)",{"$f":"C17*C18","v":0},{"$f":"D17*D18","v":0},{"$f":"E17*E18","v":0},{"$f":"F17*F18","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"AI17*AI18","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,"Forecast Price (p/kWh/d)",{"$f":"VLOOKUP(C3,Data!B:C,2,FALSE)","v":1E-3},{"$f":"C27","v":1E-3},{"$f":"D27","v":1E-3},1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3]
[null,"Non-Discounted Revenue (£)",{"$f":"C27*C25*C17/100","v":0},{"$f":"D27*D25*D17/100","v":0},0,0,0,0,0,0,0,0,0,{"$f":"N27*N25*N17/100","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"AT27*AT25*AT17/100","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,"Discounted Revenue (£)",{"$f":"C28/((1+$C10)^(C13-1))","v":0},{"$f":"D28/((1+$C10)^(D13-1))","v":0},0,{"$f":"F28/((1+$C10)^(F13-1))","v":0},{"$f":"G28/((1+$C10)^(G13-1))","v":0},{"$f":"H28/((1+$C10)^(H13-1))","v":0},{"$f":"I28/((1+$C10)^(I13-1))","v":0},{"$f":"J28/((1+$C10)^(J13-1))","v":0},{"$f":"K28/((1+$C10)^(K13-1))","v":0},{"$f":"L28/((1+$C10)^(L13-1))","v":0},{"$f":"M28/((1+$C10)^(M13-1))","v":0},{"$f":"N28/((1+$C10)^(N13-1))","v":0},{"$f":"O28/((1+$C10)^(O13-1))","v":0},{"$f":"P28/((1+$C10)^(P13-1))","v":0},{"$f":"Q28/((1+$C10)^(Q13-1))","v":0},{"$f":"R28/((1+$C10)^(R13-1))","v":0},{"$f":"S28/((1+$C10)^(S13-1))","v":0},{"$f":"T28/((1+$C10)^(T13-1))","v":0},{"$f":"U28/((1+$C10)^(U13-1))","v":0},{"$f":"V28/((1+$C10)^(V13-1))","v":0},{"$f":"W28/((1+$C10)^(W13-1))","v":0},{"$f":"X28/((1+$C10)^(X13-1))","v":0},{"$f":"Y28/((1+$C10)^(Y13-1))","v":0},{"$f":"Z28/((1+$C10)^(Z13-1))","v":0},{"$f":"AA28/((1+$C10)^(AA13-1))","v":0},{"$f":"AB28/((1+$C10)^(AB13-1))","v":0},{"$f":"AC28/((1+$C10)^(AC13-1))","v":0},{"$f":"AD28/((1+$C10)^(AD13-1))","v":0},{"$f":"AE28/((1+$C10)^(AE13-1))","v":0},{"$f":"AF28/((1+$C10)^(AF13-1))","v":0},{"$f":"AG28/((1+$C10)^(AG13-1))","v":0},{"$f":"AH28/((1+$C10)^(AH13-1))","v":0},{"$f":"AI28/((1+$C10)^(AI13-1))","v":0},{"$f":"AJ28/((1+$C10)^(AJ13-1))","v":0},{"$f":"AK28/((1+$C10)^(AK13-1))","v":0},{"$f":"AL28/((1+$C10)^(AL13-1))","v":0},{"$f":"AM28/((1+$C10)^(AM13-1))","v":0},{"$f":"AN28/((1+$C10)^(AN13-1))","v":0},{"$f":"AO28/((1+$C10)^(AO13-1))","v":0},{"$f":"AP28/((1+$C10)^(AP13-1))","v":0},{"$f":"AQ28/((1+$C10)^(AQ13-1))","v":0},{"$f":"AR28/((1+$C10)^(AR13-1))","v":0},{"$f":"AS28/((1+$C10)^(AS13-1))","v":0},{"$f":"AT28/((1+$C10)^(AT13-1))","v":0},{"$f":"AU28/((1+$C10)^(AU13-1))","v":0},{"$f":"AV28/((1+$C10)^(AV13-1))","v":0},{"$f":"AW28/((1+$C10)^(AW13-1))","v":0},{"$f":"AX28/((1+$C10)^(AX13-1))","v":0},{"$f":"AY28/((1+$C10)^(AY13-1))","v":0},{"$f":"AZ28/((1+$C10)^(AZ13-1))","v":0},{"$f":"BA28/((1+$C10)^(BA13-1))","v":0},{"$f":"BB28/((1+$C10)^(BB13-1))","v":0},{"$f":"BC28/((1+$C10)^(BC13-1))","v":0},{"$f":"BD28/((1+$C10)^(BD13-1))","v":0},{"$f":"BE28/((1+$C10)^(BE13-1))","v":0},{"$f":"BF28/((1+$C10)^(BF13-1))","v":0},{"$f":"BG28/((1+$C10)^(BG13-1))","v":0},{"$f":"BH28/((1+$C10)^(BH13-1))","v":0},{"$f":"BI28/((1+$C10)^(BI13-1))","v":0},{"$f":"BJ28/((1+$C10)^(BJ13-1))","v":0}]
[null,"NPV",{"$f":"SUM(C29:BJ29)","v":0}]
[]
[null,"Output",null,null,null,null,null,null,null,null,null,"possible outcomes for test"]
[null,"Test Passed with no premium?",{"$f":"IF(C11>=C8,\"yes\",\"no\")","v":"yes"},null,"if the NPV of User Revenue is >= the required User commitment then the test is passed",null,null,null,null,null,null,"yes","no"]
[null,null,null,null,"The premium will be 0 if the NPV of User Revenue already is >= the required User commitment"]
[null,"Premium Calculation"]
[null,"Shortfall (£)",{"$f":"MAX((C8)-C30,0)","v":0}]
[null,"Total Capacity (kWh)",{"$f":"SUM(C26:BJ26)","v":0}]
[null,"Premium (p/kWh)",5.4210108624275222E-20]
[]
[null,"Calculated Premium Shortfall (£)",{"$f":"$C$38*((1-$C10)^(C13-1))*C26/100","v":0},{"$f":"$C$38*((1-$C10)^(D13-1))*D26/100","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,"Total Shortfall Collected (£)",{"$f":"SUM(C40:BJ40)","v":0}]

{"sheet":"LTSR","index":2,"n_rows":202,"n_cols":106,"rows_kept":202,"cut":false,"hidden":false,"merged":[[6,102,6,105],[7,102,7,105],[7,98,7,101],[6,62,6,65],[6,70,6,73],[7,82,7,85],[6,82,6,85],[6,86,6,89],[6,90,6,93],[6,94,6,97],[6,98,6,101],[7,62,7,65],[7,70,7,73],[6,74,6,77],[6,50,6,53],[7,50,7,53],[7,78,7,81],[6,78,6,81],[7,22,7,25],[7,74,7,77],[7,10,7,13],[6,26,6,29],[7,94,7,97],[6,66,6,69],[7,90,7,93],[6,14,6,17],[6,18,6,21],[7,86,7,89],[6,58,6,61],[7,58,7,61],[6,38,6,41],[7,38,7,41],[6,42,6,45],[7,42,7,45],[6,54,6,57],[7,54,7,57],[7,18,7,21],[7,26,7,29],[7,66,7,69],[7,14,7,17],[6,2,6,5],[6,6,6,9],[7,30,7,33],[6,34,6,37],[6,46,6,49],[7,46,7,49],[7,2,7,5],[7,6,7,9],[7,34,7,37],[6,22,6,25],[6,30,6,33],[6,10,6,13]]}
[null,"Allocation of Obligated Entry Capacity and Release Obligation Summary Report"]
[]
[]
[null,"Monthly Report as @ 1st October 2019"]
[null,"Units: UK standard units used i.e. kWh (with a combustion reference temperature of 288.15 K)"]
[]
[null,"Month","Avonmouth",null,null,null,"Bacton IP",null,null,null,"Bacton UKCS",null,null,null,"Burton Point",null,null,null,"Barrow",null,null,null,"Barton Stacey",null,null,null,"Canonbie",null,null,null,"Cheshire",null,null,null,"Caythorpe",null,null,null,"Dynevor Arms",null,null,null,"Easington (incl. Rough)",null,null,null,"Fleetwood",null,null,null,"Glenmavis",null,null,null,"Garton",null,null,null,"Hole House Farm",null,null,null,"Hatfield Moor (onshore)",null,null,null,"Hornsea",null,null,null,"Hatfield Moor (storage)",null,null,null,"Isle of Grain",null,null,null,"Milford Haven",null,null,null,"Murrow",null,null,null,"Partington",null,null,null,"St Fergus",null,null,null,"Teesside",null,null,null,"Theddlethorpe",null,null,null,"Wytch Farm"]
[null,null,"AV",null,null,null,"BI",null,null,null,"BU",null,null,null,"BP",null,null,null,"BR",null,null,null,"BS",null,null,null,"CB",null,null,null,"CH",null,null,null,"CT",null,null,null,"DA",null,null,null,"EA",null,null,null,"FL",null,null,null,"GM",null,null,null,"GR",null,null,null,"HH",null,null,null,"HM",null,null,null,"HS",null,null,null,"HT",null,null,null,"IG",null,null,null,"MH",null,null,null,"MU",null,null,null,"PR",null,null,null,"SF",null,null,null,"TE",null,null,null,"TH",null,null,null,"WF"]
[null,null,"Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated","Non-Incremental","Legacy Incremental","Funded Incremental","Total Obligated"]
[null,null,"kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d"]
[null,"2019-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,{"$f":"542700000+13567500","v":556267500},0,0,{"$f":"542700000+13567500","v":556267500},90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2019-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2019-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2020-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2021-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2022-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2023-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2024-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,{"$f":"542700000+13567500","v":556267500},0,0,{"$f":"542700000+13567500","v":556267500},90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,500000,0,0,500000,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2025-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,0,950000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2026-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2027-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2028-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2029-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,{"$f":"542700000+13567500","v":556267500},0,0,{"$f":"542700000+13567500","v":556267500},90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2030-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-10-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-11-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2031-12-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-01-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-02-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-03-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-04-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-05-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-06-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-07-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-08-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-09-01",179300000,0,0,179300000,1297800000,0,0,1297800000,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-10-01",179300000,0,0,179300000,1297800001,0,0,1297800001,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-11-01",179300000,0,0,179300000,1297800002,0,0,1297800002,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2032-12-01",179300000,0,0,179300000,1297800003,0,0,1297800003,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-01-01",179300000,0,0,179300000,1297800004,0,0,1297800004,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-02-01",179300000,0,0,179300000,1297800005,0,0,1297800005,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-03-01",179300000,0,0,179300000,1297800006,0,0,1297800006,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-04-01",179300000,0,0,179300000,1297800007,0,0,1297800007,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-05-01",179300000,0,0,179300000,1297800008,0,0,1297800008,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-06-01",179300000,0,0,179300000,1297800009,0,0,1297800009,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-07-01",179300000,0,0,179300000,1297800010,0,0,1297800010,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-08-01",179300000,0,0,179300000,1297800011,0,0,1297800011,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-09-01",179300000,0,0,179300000,1297800012,0,0,1297800012,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-10-01",179300000,0,0,179300000,1297800001,0,0,1297800001,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-11-01",179300000,0,0,179300000,1297800002,0,0,1297800002,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2033-12-01",179300000,0,0,179300000,1297800003,0,0,1297800003,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-01-01",179300000,0,0,179300000,1297800004,0,0,1297800004,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-02-01",179300000,0,0,179300000,1297800005,0,0,1297800005,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-03-01",179300000,0,0,179300000,1297800006,0,0,1297800006,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-04-01",179300000,0,0,179300000,1297800007,0,0,1297800007,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-05-01",179300000,0,0,179300000,1297800008,0,0,1297800008,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-06-01",179300000,0,0,179300000,1297800009,0,0,1297800009,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-07-01",179300000,0,0,179300000,1297800010,0,0,1297800010,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-08-01",179300000,0,0,179300000,1297800011,0,0,1297800011,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-09-01",179300000,0,0,179300000,1297800012,0,0,1297800012,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-10-01",179300000,0,0,179300000,1297800013,0,0,1297800013,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-11-01",179300000,0,0,179300000,1297800014,0,0,1297800014,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2034-12-01",179300000,0,0,179300000,1297800015,0,0,1297800015,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-01-01",179300000,0,0,179300000,1297800016,0,0,1297800016,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-02-01",179300000,0,0,179300000,1297800017,0,0,1297800017,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-03-01",179300000,0,0,179300000,1297800018,0,0,1297800018,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-04-01",179300000,0,0,179300000,1297800019,0,0,1297800019,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-05-01",179300000,0,0,179300000,1297800020,0,0,1297800020,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-06-01",179300000,0,0,179300000,1297800021,0,0,1297800021,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-07-01",179300000,0,0,179300000,1297800022,0,0,1297800022,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-08-01",179300000,0,0,179300000,1297800023,0,0,1297800023,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]
[null,"2035-09-01",179300000,0,0,179300000,1297800024,0,0,1297800024,485600000,0,0,485600000,73500000,0,0,73500000,340010000,0,0,340010000,172600000,0,0,172600000,0,0,0,0,556267500,0,0,556267500,90000000,0,0,90000000,49000000,0,0,49000000,1407150000,0,0,1407150000,350000000,0,0,350000000,99000000,0,0,99000000,420000000,0,0,420000000,296600000,0,0,296600000,300000,0,0,300000,233100000,0,0,233100000,25000000,0,0,25000000,699680000,0,0,699680000,950000000,0,163000000,1113000000,0,0,0,0,201432500,0,0,201432500,1670700000,0,0,1670700000,445090000,0,0,445090000,610700000,0,0,610700000,3300000,0,0,3300000]

{"sheet":"Sold","index":3,"n_rows":202,"n_cols":132,"rows_kept":202,"cut":false,"hidden":false,"merged":[[6,127,6,131],[7,127,7,131],[6,102,6,106],[6,97,6,101],[6,2,6,6],[7,2,7,6],[6,77,6,81],[6,82,6,86],[6,67,6,71],[6,72,6,76],[6,57,6,61],[6,42,6,46],[6,7,6,11],[7,67,7,71],[7,72,7,76],[7,57,7,61],[6,87,6,91],[6,92,6,96],[7,87,7,91],[7,92,7,96],[7,102,7,106],[7,97,7,101],[7,77,7,81],[7,82,7,86],[6,107,6,111],[7,107,7,111],[6,122,6,126],[7,122,7,126],[6,112,6,116],[7,112,7,116],[6,117,6,121],[7,117,7,121],[7,7,7,11],[6,37,6,41],[7,37,7,41],[6,32,6,36],[7,32,7,36],[6,22,6,26],[7,22,7,26],[6,12,6,16],[7,12,7,16],[6,27,6,31],[7,27,7,31],[6,17,6,21],[7,17,7,21],[7,42,7,46],[6,62,6,66],[7,62,7,66],[6,47,6,51],[7,47,7,51],[6,52,6,56],[7,52,7,56]]}
[null,"Allocation of Obligated Entry Capacity and Release Obligation Summary Report"]
[]
[]
[null,"Monthly Report as @ 1st October 2019"]
[null,"Units: UK standard units used i.e. kWh (with a combustion reference temperature of 288.15 K)"]
[]
[null,"Month","Avonmouth",null,null,null,null,"Bacton IP",null,null,null,null,"Bacton UKCS",null,null,null,null,"Burton Point",null,null,null,null,"Barrow",null,null,null,null,"Barton Stacey",null,null,null,null,"Canonbie",null,null,null,null,"Cheshire",null,null,null,null,"Caythorpe",null,null,null,null,"Dynevor Arms",null,null,null,null,"Easington (incl. Rough)",null,null,null,null,"Fleetwood",null,null,null,null,"Glenmavis",null,null,null,null,"Garton",null,null,null,null,"Hole House Farm",null,null,null,null,"Hatfield Moor (onshore)",null,null,null,null,"Hornsea",null,null,null,null,"Hatfield Moor (storage)",null,null,null,null,"Isle of Grain",null,null,null,null,"Milford Haven",null,null,null,null,"Murrow",null,null,null,null,"Partington",null,null,null,null,"St Fergus",null,null,null,null,"Teesside",null,null,null,null,"Theddlethorpe",null,null,null,null,"Wytch Farm"]
[null,null,"AV",null,null,null,null,"BI",null,null,null,null,"BU",null,null,null,null,"BP",null,null,null,null,"BR",null,null,null,null,"BS",null,null,null,null,"CB",null,null,null,null,"CH",null,null,null,null,"CT",null,null,null,null,"DA",null,null,null,null,"EA",null,null,null,null,"FL",null,null,null,null,"GM",null,null,null,null,"GR",null,null,null,null,"HH",null,null,null,null,"HM",null,null,null,null,"HS",null,null,null,null,"HT",null,null,null,null,"IG",null,null,null,null,"MH",null,null,null,null,"MU",null,null,null,null,"PR",null,null,null,null,"SF",null,null,null,null,"TE",null,null,null,null,"TH",null,null,null,null,"WF"]
[null,null,"Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold","Monthly Release Obligation","Obligated Firm Quantity Sold","Quantity Reserved","Obligated Quantity Unsold and Not Reserved","Non-Obligated Sold"]
[null,null,"kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d","kWh/d"]
[null,"2019-10-01",179300000,0,0,179300000,0,1297800000,79931000,0,1217869000,0,485600000,373886479,0,111713521,0,73500000,13138017,0,60361983,0,340010000,57932198,0,282077802,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1045413727,0,361736273,0,350000000,300000000,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,0,0,0,0,0,201432500,0,0,{"$f":"DD11-DE11","v":201432500},0,1670700000,{"$f":"123268367+100000","v":123368367},0,{"$f":"DI11-DJ11","v":1547331633},0,445090000,90791941,0,354298059,0,610700000,9200000,0,601500000,0,3300000,0,0,3300000,0]
[null,"2019-11-01",179300000,0,0,179300000,0,1297800000,79931000,0,1217869000,0,485600000,373886479,0,111713521,0,73500000,13138017,0,60361983,0,340010000,57932198,0,282077802,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1045413727,0,361736273,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,{"$f":"123268367+100000","v":123368367},0,{"$f":"DI12-DJ12","v":1547331633},0,445090000,90791941,0,354298059,0,610700000,9200000,0,601500000,0,3300000,0,0,3300000,0]
[null,"2019-12-01",179300000,0,0,179300000,0,1297800000,79931000,0,1217869000,0,485600000,373886479,0,111713521,0,73500000,13138017,0,60361983,0,340010000,57932198,0,282077802,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1045413727,0,361736273,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,{"$f":"123268367+100000","v":123368367},0,1547331633,0,445090000,90791941,0,354298059,0,610700000,9200000,0,601500000,0,3300000,0,0,3300000,0]
[null,"2020-01-01",179300000,0,0,179300000,0,1297800000,277207179,0,1020592821,0,485600000,485600000,0,0,0,73500000,12441963,0,61058037,0,340010000,86357101,0,253652899,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1300950000,0,106200000,7199999,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,{"$f":"118774128+100000","v":118874128},0,1551825872,0,445090000,78862832,0,366227168,0,610700000,8800000,0,601900000,0,3300000,0,0,3300000,0]
[null,"2020-02-01",179300000,0,0,179300000,0,1297800000,277207179,0,1020592821,0,485600000,485600000,0,0,0,73500000,12441963,0,61058037,0,340010000,86357101,0,253652899,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1300950000,0,106200000,7199999,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,{"$f":"118774128+100000","v":118874128},0,1551825872,0,445090000,78862832,0,366227168,0,610700000,8800000,0,601900000,0,3300000,0,0,3300000,0]
[null,"2020-03-01",179300000,0,0,179300000,0,1297800000,277207179,0,1020592821,0,485600000,485600000,0,0,0,73500000,12441963,0,61058037,0,340010000,86357101,0,253652899,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1300950000,0,106200000,7199999,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,{"$f":"118774128+100000","v":118874128},0,1551825872,0,445090000,78862832,0,366227168,0,610700000,8800000,0,601900000,0,3300000,0,0,3300000,0]
[null,"2020-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,49692846,0,435907154,0,73500000,11941675,0,61558325,0,340010000,15214386,0,324795614,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,234965073,0,1172184927,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,903000000,0,47000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,{"$f":"21774128+100000","v":21874128},0,1648825872,0,445090000,79927338,0,365162662,0,610700000,8300000,0,602400000,0,3300000,0,0,3300000,0]
[null,"2020-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,49692846,0,435907154,0,73500000,11941675,0,61558325,0,340010000,15214386,0,324795614,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,234965073,0,1172184927,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,903000000,0,47000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,21874128,0,1648825872,0,445090000,79927338,0,365162662,0,610700000,8300000,0,602400000,0,3300000,0,0,3300000,0]
[null,"2020-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,49692846,0,435907154,0,73500000,11941675,0,61558325,0,340010000,15214386,0,324795614,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,234965073,0,1172184927,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,903000000,0,47000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,21874128,0,1648825872,0,445090000,79927338,0,365162662,0,610700000,8300000,0,602400000,0,3300000,0,0,3300000,0]
[null,"2020-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,46192846,0,439407154,0,73500000,8548412,0,64951588,0,340010000,20594941,0,319415059,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,233665073,0,1173484927,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,903000000,0,47000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,21874128,0,1648825872,0,445090000,76652699,0,368437301,0,610700000,7900000,0,602800000,0,3300000,0,0,3300000,0]
[null,"2020-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,46192846,0,439407154,0,73500000,8548412,0,64951588,0,340010000,20594941,0,319415059,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,233665073,0,1173484927,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,903000000,0,47000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,21874128,0,1648825872,0,445090000,76652699,0,368437301,0,610700000,7900000,0,602800000,0,3300000,0,0,3300000,0]
[null,"2020-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,46192846,0,439407154,0,73500000,8548412,0,64951588,0,340010000,20594941,0,319415059,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,233665073,0,1173484927,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,903000000,0,47000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,21874128,0,1648825872,0,445090000,76652699,0,368437301,0,610700000,7900000,0,602800000,0,3300000,0,0,3300000,0]
[null,"2020-10-01",179300000,0,0,179300000,0,1297800000,107932000,0,1189868000,0,485600000,340776179,0,144823821,0,73500000,8374398,0,65125602,0,340010000,17456116,0,322553884,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1021941357,0,385208643,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,98722536,0,1571977464,0,445090000,76545995,0,368544005,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2020-11-01",179300000,0,0,179300000,0,1297800000,107932000,0,1189868000,0,485600000,340776179,0,144823821,0,73500000,8374398,0,65125602,0,340010000,17456116,0,322553884,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1021941357,0,385208643,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,98722536,0,1571977464,0,445090000,76545995,0,368544005,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2020-12-01",179300000,0,0,179300000,0,1297800000,107932000,0,1189868000,0,485600000,340776179,0,144823821,0,73500000,8374398,0,65125602,0,340010000,17456116,0,322553884,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1021941357,0,385208643,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,98722536,0,1571977464,0,445090000,76545995,0,368544005,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-01-01",179300000,0,0,179300000,0,1297800000,263438833,0,1034361167,0,485600000,485600000,0,0,0,73500000,8156882,0,65343118,0,340010000,74112765,0,265897235,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1300950000,0,106200000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,90116104,0,1580583896,0,445090000,43636027,0,401453973,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-02-01",179300000,0,0,179300000,0,1297800000,263438833,0,1034361167,0,485600000,485600000,0,0,0,73500000,8156882,0,65343118,0,340010000,74112765,0,265897235,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1300950000,0,106200000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,90116104,0,1580583896,0,445090000,43636027,0,401453973,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-03-01",179300000,0,0,179300000,0,1297800000,263438833,0,1034361167,0,485600000,485600000,0,0,0,73500000,8156882,0,65343118,0,340010000,74112765,0,265897235,0,172600000,90000000,0,82600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1300950000,0,106200000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,950000000,0,0,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,90116104,0,1580583896,0,445090000,43636027,0,401453973,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,9823500,0,475776500,0,73500000,7025794,0,66474206,0,340010000,9741535,0,330268465,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,187417551,0,1219732449,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,13216104,0,1657483896,0,445090000,43959425,0,401130575,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,9823500,0,475776500,0,73500000,7025794,0,66474206,0,340010000,9741535,0,330268465,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,187417551,0,1219732449,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,13216104,0,1657483896,0,445090000,43959425,0,401130575,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,9823500,0,475776500,0,73500000,7025794,0,66474206,0,340010000,9741535,0,330268465,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,187417551,0,1219732449,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,13216104,0,1657483896,0,445090000,43959425,0,401130575,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,9823500,0,475776500,0,73500000,5002887,0,68497113,0,340010000,13927493,0,326082507,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,186917551,0,1220232449,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,13216104,0,1657483896,0,445090000,43272240,0,401817760,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,9823500,0,475776500,0,73500000,5002887,0,68497113,0,340010000,13927493,0,326082507,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,186917551,0,1220232449,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,13216104,0,1657483896,0,445090000,43272240,0,401817760,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,9823500,0,475776500,0,73500000,5002887,0,68497113,0,340010000,13927493,0,326082507,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,186917551,0,1220232449,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,622600000,0,77080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,13216104,0,1657483896,0,445090000,43272240,0,401817760,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-10-01",179300000,0,0,179300000,0,1297800000,27150000,0,1270650000,0,485600000,332718455,0,{"$f":"M35-N35","v":152881545},0,73500000,0,0,73500000,0,340010000,12844254,0,327165746,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1017755291,0,389394709,0,350000000,20350000,0,{"$f":"BF35-BG35","v":329650000},0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,45836668,0,1624863332,0,445090000,{"$f":"42140885+80823094","v":122963979},0,{"$f":"DN35-DO35","v":322126021},0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-11-01",179300000,0,0,179300000,0,1297800000,27150000,0,1270650000,0,485600000,332718455,0,{"$f":"M36-N36","v":152881545},0,73500000,0,0,73500000,0,340010000,12844254,0,327165746,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1017755291,0,389394709,0,350000000,20350000,0,{"$f":"BF36-BG36","v":329650000},0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,45836668,0,1624863332,0,445090000,{"$f":"42140885+80823094","v":122963979},0,{"$f":"DN36-DO36","v":322126021},0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2021-12-01",179300000,0,0,179300000,0,1297800000,27150000,0,1270650000,0,485600000,332718455,0,152881545,0,73500000,0,0,73500000,0,340010000,12844254,0,327165746,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1017755291,0,389394709,0,350000000,20350000,0,329650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,45836668,0,1624863332,0,445090000,{"$f":"42140885+80823094","v":122963979},0,322126021,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-01-01",179300000,0,0,179300000,0,1297800000,151502392,0,1146297608,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,70068930,0,269941070,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1266435000,0,140715000,0,350000000,20450000,0,329550000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,42936668,0,1627763332,0,445090000,{"$f":"31997084+78472376","v":110469460},0,334620540,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-02-01",179300000,0,0,179300000,0,1297800000,151502392,0,1146297608,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,70068930,0,269941070,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1266435000,0,140715000,0,350000000,20450000,0,329550000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,42936668,0,1627763332,0,445090000,{"$f":"31997084+78472376","v":110469460},0,334620540,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-03-01",179300000,0,0,179300000,0,1297800000,151502392,0,1146297608,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,70068930,0,269941070,0,172600000,72000000,0,100600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1266435000,0,140715000,0,350000000,20450000,0,329550000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,42936668,0,1627763332,0,445090000,{"$f":"31997084+78472376","v":110469460},0,334620540,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,23893121,0,461706879,0,73500000,0,0,73500000,0,340010000,7442443,0,332567557,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,42473436,0,1364676564,0,350000000,20350000,0,329650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,9600000,0,1661100000,0,445090000,{"$f":"31543615+77996564","v":109540179},0,335549821,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,23893121,0,461706879,0,73500000,0,0,73500000,0,340010000,7442443,0,332567557,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,42473436,0,1364676564,0,350000000,20350000,0,329650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,9600000,0,1661100000,0,445090000,{"$f":"31543615+77996564","v":109540179},0,335549821,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,23893121,0,461706879,0,73500000,0,0,73500000,0,340010000,7442443,0,332567557,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,42473436,0,1364676564,0,350000000,20350000,0,329650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,9600000,0,1661100000,0,445090000,{"$f":"31543615+77996564","v":109540179},0,335549821,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,38993121,0,446606879,0,73500000,0,0,73500000,0,340010000,10992320,0,329017680,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,41973436,0,1365176564,0,350000000,20350000,0,329650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,9600000,0,1661100000,0,445090000,{"$f":"30399384+78355975","v":108755359},0,336334641,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,38993121,0,446606879,0,73500000,0,0,73500000,0,340010000,10992320,0,329017680,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,41973436,0,1365176564,0,350000000,20350000,0,329650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,9600000,0,1661100000,0,445090000,{"$f":"30399384+78355975","v":108755359},0,336334641,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,38993121,0,446606879,0,73500000,0,0,73500000,0,340010000,10992320,0,329017680,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,41973436,0,1365176564,0,350000000,20350000,0,329650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,350000000,0,600000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,9600000,0,1661100000,0,445090000,{"$f":"30399384+78355975","v":108755359},0,336334641,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,329476454,0,156123546,0,73500000,0,0,73500000,0,340010000,10153146,0,329856854,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1019293580,0,387856420,0,350000000,144450000,0,205550000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,34812775,0,1635887225,0,445090000,{"$f":"30571100+78172387","v":108743487},0,336346513,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,329476454,0,156123546,0,73500000,0,0,73500000,0,340010000,10153146,0,329856854,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1019293580,0,387856420,0,350000000,144450000,0,205550000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,34812775,0,1635887225,0,445090000,{"$f":"30571100+78172387","v":108743487},0,336346513,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2022-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,329476454,0,156123546,0,73500000,0,0,73500000,0,340010000,10153146,0,329856854,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1019293580,0,387856420,0,350000000,144450000,0,205550000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,34812775,0,1635887225,0,445090000,{"$f":"30571100+78172387","v":108743487},0,336346513,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-01-01",179300000,0,0,179300000,0,1297800000,116298603,0,1181501397,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,59548791,0,280461209,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1268873557,0,138276443,0,350000000,144350000,0,205650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,34447591,0,1636252409,0,445090000,68798055,0,376291945,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-02-01",179300000,0,0,179300000,0,1297800000,116298603,0,1181501397,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,59548791,0,280461209,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1268873557,0,138276443,0,350000000,144350000,0,205650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,34447591,0,1636252409,0,445090000,68798055,0,376291945,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-03-01",179300000,0,0,179300000,0,1297800000,116298603,0,1181501397,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,59548791,0,280461209,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1268873557,0,138276443,0,350000000,144350000,0,205650000,0,99000000,0,0,99000000,0,420000000,420000000,0,0,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,205790000,0,27310000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,34447591,0,1636252409,0,445090000,68798055,0,376291945,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,15878978,0,469721022,0,73500000,0,0,73500000,0,340010000,977111,0,339032889,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,38752543,0,1368397457,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,10732069,0,1659967931,0,445090000,{"$f":"2749965+65008636","v":67758601},0,377331399,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,15878978,0,469721022,0,73500000,0,0,73500000,0,340010000,977111,0,339032889,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,38752543,0,1368397457,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,10732069,0,1659967931,0,445090000,{"$f":"2749965+65008636","v":67758601},0,377331399,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,15878978,0,469721022,0,73500000,0,0,73500000,0,340010000,977111,0,339032889,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,38752543,0,1368397457,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,10732069,0,1659967931,0,445090000,{"$f":"2749965+65008636","v":67758601},0,377331399,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,30978978,0,454621022,0,73500000,0,0,73500000,0,340010000,1557398,0,338452602,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,38752543,0,1368397457,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,10732069,0,1659967931,0,445090000,{"$f":"2669009+64910945","v":67579954},0,377510046,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,30978978,0,454621022,0,73500000,0,0,73500000,0,340010000,1557398,0,338452602,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,38752543,0,1368397457,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,10732069,0,1659967931,0,445090000,{"$f":"2669009+64910945","v":67579954},0,377510046,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,30978978,0,454621022,0,73500000,0,0,73500000,0,340010000,1557398,0,338452602,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,38752543,0,1368397457,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,582600000,0,117080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,10732069,0,1659967931,0,445090000,{"$f":"2669009+64910945","v":67579954},0,377510046,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,321462311,0,164137689,0,73500000,0,0,73500000,0,340010000,1521062,0,338488938,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,882208146,0,524941854,0,350000000,179050000,0,170950000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,854500000,0,95500000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,29401496,0,1641298504,0,445090000,{"$f":"2592351+64574137","v":67166488},0,377923512,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,321462311,0,164137689,0,73500000,0,0,73500000,0,340010000,1521062,0,338488938,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,882208146,0,524941854,0,350000000,179050000,0,170950000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,854500000,0,95500000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,29401496,0,1641298504,0,445090000,{"$f":"2592351+64574137","v":67166488},0,377923512,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2023-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,321462311,0,164137689,0,73500000,0,0,73500000,0,340010000,1521062,0,338488938,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,882208146,0,524941854,0,350000000,179050000,0,170950000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,664300000,0,35380000,0,950000000,854500000,0,95500000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,29401496,0,1641298504,0,445090000,{"$f":"2592351+64574137","v":67166488},0,377923512,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-01-01",179300000,0,0,179300000,0,1297800000,115983333,0,1181816667,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,59502720,0,280507280,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1013169559,0,393980441,0,350000000,179050000,0,170950000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,24169427,0,1646530573,0,445090000,{"$f":"2517455+54403637","v":56921092},0,388168908,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-02-01",179300000,0,0,179300000,0,1297800000,115983333,0,1181816667,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,59502720,0,280507280,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1013169559,0,393980441,0,350000000,179050000,0,170950000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,24169427,0,1646530573,0,445090000,{"$f":"2517455+54403637","v":56921092},0,388168908,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-03-01",179300000,0,0,179300000,0,1297800000,115983333,0,1181816667,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,59502720,0,280507280,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,1013169559,0,393980441,0,350000000,179050000,0,170950000,0,99000000,0,0,99000000,0,420000000,140000000,0,280000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,22000000,0,3000000,0,699680000,664300000,0,35380000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,24169427,0,1646530573,0,445090000,{"$f":"2517455+54403637","v":56921092},0,388168908,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,322212531,0,163387469,0,73500000,0,0,73500000,0,340010000,950471,0,339059529,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,35708146,0,1371441854,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,4248558,0,1666451442,0,445090000,{"$f":"1222869+53949307","v":55172176},0,389917824,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,322212531,0,163387469,0,73500000,0,0,73500000,0,340010000,950471,0,339059529,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,35708146,0,1371441854,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,4248558,0,1666451442,0,445090000,{"$f":"1222869+53949307","v":55172176},0,389917824,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,322212531,0,163387469,0,73500000,0,0,73500000,0,340010000,950471,0,339059529,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,35708146,0,1371441854,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,4248558,0,1666451442,0,445090000,{"$f":"1222869+53949307","v":55172176},0,389917824,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,31729108,0,453870892,0,73500000,0,0,73500000,0,340010000,1511991,0,338498009,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,35208146,0,1371941854,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,4248558,0,1666451442,0,445090000,{"$f":"1113028+53711569","v":54824597},0,390265403,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,31729108,0,453870892,0,73500000,0,0,73500000,0,340010000,1511991,0,338498009,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,35208146,0,1371941854,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,4248558,0,1666451442,0,445090000,{"$f":"1113028+53711569","v":54824597},0,390265403,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,31729108,0,453870892,0,73500000,0,0,73500000,0,340010000,1511991,0,338498009,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,35208146,0,1371941854,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,4248558,0,1666451442,0,445090000,{"$f":"1113028+53711569","v":54824597},0,390265403,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,322212531,0,163387469,0,73500000,0,0,73500000,0,340010000,1476388,0,338533612,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,821640612,0,585509388,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,492600000,0,207080000,0,950000000,760000000,0,190000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,6964905,0,1663735095,0,445090000,{"$f":"1034998+53290750","v":54325748},0,390764252,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,322212531,0,163387469,0,73500000,0,0,73500000,0,340010000,1476388,0,338533612,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,821640612,0,585509388,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,492600000,0,207080000,0,950000000,760000000,0,190000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,6964905,0,1663735095,0,445090000,{"$f":"1034998+53290750","v":54325748},0,390764252,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2024-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,322212531,0,163387469,0,73500000,0,0,73500000,0,340010000,1476388,0,338533612,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,821640612,0,585509388,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,492600000,0,207080000,0,950000000,760000000,0,190000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,6964905,0,1663735095,0,445090000,{"$f":"1034998+53290750","v":54325748},0,390764252,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-01-01",179300000,0,0,179300000,0,1297800000,115983333,0,1181816667,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,875240612,0,531909388,0,385000000,350000000,0,35000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,22000000,0,3000000,0,699680000,492600000,0,207080000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,6475157,0,1664224843,0,445090000,{"$f":"845659+46002896","v":46848555},0,398241445,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-02-01",179300000,0,0,179300000,0,1297800000,115983333,0,1181816667,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,875240612,0,531909388,0,385000000,350000000,0,35000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,22000000,0,3000000,0,699680000,492600000,0,207080000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,{"$f":"DD75-DE75","v":201432500},0,1670700000,6475157,0,1664224843,0,445090000,{"$f":"845659+46002896","v":46848555},0,398241445,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-03-01",179300000,0,0,179300000,0,1297800000,115983333,0,1181816667,0,485600000,485600000,0,0,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,90000000,0,0,0,49000000,0,0,49000000,0,1407150000,875240612,0,531909388,0,385000000,350000000,0,35000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,22000000,0,3000000,0,699680000,492600000,0,207080000,0,950000000,855000000,0,95000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,6475157,0,1664224843,0,445090000,{"$f":"845659+46002896","v":46848555},0,398241445,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,14607499,0,470992501,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,32522171,0,1374627829,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"798044+45286389","v":46084433},0,399005567,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,14607499,0,470992501,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,32522171,0,1374627829,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"798044+45286389","v":46084433},0,399005567,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,14607499,0,470992501,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,32522171,0,1374627829,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,522600000,0,177080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"798044+45286389","v":46084433},0,399005567,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,29707499,0,455892501,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,32122171,0,1375027829,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"773857+45143433","v":45917290},0,399172710,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,29707499,0,455892501,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,32122171,0,1375027829,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"773857+45143433","v":45917290},0,399172710,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,29707499,0,455892501,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,32122171,0,1375027829,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,950000000,0,0,950000000,0,500000,0,0,0,500000,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"773857+45143433","v":45917290},0,399172710,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,305583333,0,180016667,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,758776761,0,648373239,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,950000000,760000000,0,190000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"721350+44870630","v":45591980},0,399498020,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,305583333,0,180016667,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,758776761,0,648373239,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,950000000,760000000,0,190000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"721350+44870630","v":45591980},0,399498020,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2025-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,305583333,0,180016667,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,758776761,0,648373239,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,950000000,760000000,0,190000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,3758810,0,1666941190,0,445090000,{"$f":"721350+44870630","v":45591980},0,399498020,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,305583333,0,180016667,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,759665649,0,647484351,0,385000000,315000000,0,70000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38840156,0,406249844,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,305583333,0,180016667,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,759665649,0,647484351,0,385000000,315000000,0,70000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38840156,0,406249844,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,305583333,0,180016667,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,759665649,0,647484351,0,385000000,315000000,0,70000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38840156,0,406249844,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,29481205,0,1377668795,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38208532,0,406881468,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,29481205,0,1377668795,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38208532,0,406881468,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,29481205,0,1377668795,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38208532,0,406881468,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,29481205,0,1377668795,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38043600,0,407046400,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,29481205,0,1377668795,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38043600,0,407046400,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,29481205,0,1377668795,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,283440000,0,13160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,2752118,0,1667947882,0,445090000,38043600,0,407046400,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,634600000,0,772550000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,760000000,163000000,190000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,37783729,0,407306271,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,634600000,0,772550000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,760000000,163000000,190000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,37783729,0,407306271,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2026-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,634600000,0,772550000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,760000000,163000000,190000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,37783729,0,407306271,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,635488889,0,771661111,0,385000000,315000000,0,35000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,29667677,0,415422323,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,635488889,0,771661111,0,385000000,315000000,0,35000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,29667677,0,415422323,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,635488889,0,771661111,0,385000000,315000000,0,35000000,35000000,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,29667677,0,{"$f":"DN100-DO100","v":415422323},0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,20600000,0,1386550000,0,350000000,20000000,0,{"$f":"BF101-BG101","v":330000000},0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,29180135,0,415909865,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,20600000,0,1386550000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,29180135,0,415909865,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,20600000,0,1386550000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,29180135,0,415909865,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,20600000,0,1386550000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,28877158,0,416212842,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,20600000,0,1386550000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,28877158,0,416212842,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,20600000,0,1386550000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,28877158,0,416212842,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,482000000,0,925150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,110000000,163000000,840000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,27638526,0,417451474,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,482000000,0,925150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,110000000,163000000,840000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,27638526,0,417451474,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2027-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,482000000,0,925150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,110000000,163000000,840000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,27638526,0,417451474,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,482000000,0,925150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,482000000,0,925150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,482000000,0,925150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,422600000,0,277080000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,110000000,163000000,840000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,110000000,163000000,840000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2028-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,110000000,163000000,840000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,22024441,0,423065559,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,855000000,163000000,95000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,118440000,0,178160000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,350000000,0,349680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2029-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,20202401,0,424887599,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,650000000,163000000,300000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,650000000,163000000,300000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,650000000,163000000,300000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,{"$f":"DD139-DE139","v":201432500},0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2030-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,16049148,0,429040852,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2031-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,{"$f":"DN164-DO164","v":445090000},0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,{"$f":"BF165-BG165","v":330000000},0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,527677500,0,28590000,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2032-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,515565000,0,40702500,13567500,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699680000,0,0,699680000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,{"$f":"542700000+13567500","v":556267500},475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2033-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,229290000,0,120710000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,475200000,0,81067500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,20000000,0,330000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-10-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,{"$f":"542700000+13567500","v":556267500},0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-11-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2034-12-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-01-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-02-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-03-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-04-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-05-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-06-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-07-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-08-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]
[null,"2035-09-01",179300000,0,0,179300000,0,1297800000,0,0,1297800000,0,485600000,0,0,485600000,0,73500000,0,0,73500000,0,340010000,0,0,340010000,0,172600000,0,0,172600000,0,0,0,0,0,0,556267500,0,0,556267500,0,90000000,0,0,90000000,0,49000000,0,0,49000000,0,1407150000,0,0,1407150000,0,350000000,0,0,350000000,0,99000000,0,0,99000000,0,420000000,0,0,420000000,0,296600000,0,0,296600000,0,300000,0,0,300000,0,233100000,0,0,233100000,0,25000000,0,0,25000000,0,699640000,0,0,699640000,0,1113000000,0,163000000,950000000,0,0,0,0,0,0,201432500,0,0,201432500,0,1670700000,0,0,1670700000,0,445090000,0,0,445090000,0,610700000,0,0,610700000,0,3300000,0,0,3300000,0]

{"sheet":"Data","index":4,"n_rows":28,"n_cols":3,"rows_kept":28,"cut":false,"hidden":false,"merged":[]}
[]
[null,"Entry Point ","Price (p/kWh/day)"]
[null,"Avonmouth",1E-3]
[null,"Bacton IP",9.4999999999999998E-3]
[null,"Bacton UKCS",1.04E-2]
[null,"Barrow",1E-4]
[null,"Barton Stacey",1E-4]
[null,"Burton Point",1E-4]
[null,"Canonbie",1E-4]
[null,"Caythorpe",1.29E-2]
[null,"Cheshire",5.9999999999999995E-4]
[null,"Dynevor Arms",9.5999999999999992E-3]
[null,"Easington (incl. Rough)",1.6400000000000001E-2]
[null,"Fleetwood",1E-4]
[null,"Garton",1.37E-2]
[null,"Glenmavis",1.2500000000000001E-2]
[null,"Hatfield Moor (onshore)",3.8E-3]
[null,"Hatfield Moor (storage)",3.8E-3]
[null,"Hole House Farm",1E-4]
[null,"Hornsea",1.34E-2]
[null,"Isle of Grain",1E-4]
[null,"Milford Haven",2.4E-2]
[null,"Partington",1E-4]
[null,"St Fergus",5.3199999999999997E-2]
[null,"Teesside",9.1000000000000004E-3]
[null,"Theddlethorpe",1.7100000000000001E-2]
[null,"Wytch Farm",1E-4]
[null,"Murrow",1E-4]